{"id":2807,"count":1,"description":"","link":"https:\/\/asrad.pccu.edu.tw\/dbar\/keyword\/%e5%b1%b1%e8%84%88%e6%95%88%e6%87%89\/","name":"\u5c71\u8108\u6548\u61c9","slug":"%e5%b1%b1%e8%84%88%e6%95%88%e6%87%89","taxonomy":"keyword","meta":[],"_links":{"self":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/keyword\/2807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/keyword"}],"about":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/taxonomies\/keyword"}],"wp:post_type":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/doc_journal?keyword=2807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}