{"id":2806,"count":1,"description":"","link":"https:\/\/asrad.pccu.edu.tw\/dbar\/keyword\/%e8%83%bd%e9%87%8f%e5%88%86%e6%9e%90\/","name":"\u80fd\u91cf\u5206\u6790","slug":"%e8%83%bd%e9%87%8f%e5%88%86%e6%9e%90","taxonomy":"keyword","meta":[],"_links":{"self":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/keyword\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/keyword"}],"about":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/taxonomies\/keyword"}],"wp:post_type":[{"href":"https:\/\/asrad.pccu.edu.tw\/dbar\/wp-json\/wp\/v2\/doc_journal?keyword=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}